{"id":3,"count":646,"description":"","link":"https:\/\/containergardeningexpert.com\/articles\/category\/fruit-container-gardening\/","name":"Fruit Container Gardening","slug":"fruit-container-gardening","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/containergardeningexpert.com\/articles\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/containergardeningexpert.com\/articles\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/containergardeningexpert.com\/articles\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/containergardeningexpert.com\/articles\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}